{"id":1004,"date":"2012-04-20T14:33:41","date_gmt":"2012-04-20T14:33:41","guid":{"rendered":"https:\/\/bice.org\/fr\/la-resilience-en-question\/"},"modified":"2023-02-02T11:20:54","modified_gmt":"2023-02-02T10:20:54","slug":"la-resilience-en-question","status":"publish","type":"post","link":"https:\/\/bice.org\/fr\/la-resilience-en-question\/","title":{"rendered":"La r\u00e9silience en question"},"content":{"rendered":"<p><span lang=\"FR-BE\">Dans un premier temps, le <strong>Professeur Manciaux<\/strong> (Nancy) a esquiss\u00e9 les courants porteurs dont a \u00e9merg\u00e9 la r\u00e9silience, en s\u2019appuyant sur trois courants convergents\u00a0: l\u2019observation de la vie humaine, qu\u2019elle soit clinique ou non professionnelle, la litt\u00e9rature profane comme les romans et les biographies, et la r\u00e9flexion scientifique. Il est notamment int\u00e9ressant de constater que les histoires de r\u00e9silience \u2013 sans mentionner ce mot \u2013 abondent dans les litt\u00e9ratures du monde, surtout dans des p\u00e9riodes historiques difficiles, comme par exemple chez Charles Dickens. <\/span><\/p>\n<p><span lang=\"FR-BE\">L\u2019importance de l\u2019attachement de l\u2019enfant a \u00e9t\u00e9 d\u00e9velopp\u00e9e par Michel Manciaux, qui a soulign\u00e9 combien la fragilit\u00e9 humaine peut devenir une force de vie si elle est bien assum\u00e9e. Il a insist\u00e9 sur l\u2019importance de l\u2019\u00e9thique au quotidien, en terminant avec la notion de vis\u00e9e \u00e9thique selon Ricoeur\u00a0: \u00ab\u00a0<em>La vis\u00e9e de la vie bonne avec et pour autrui, dans des institutions justes\u00a0\u00bb<\/em>. <\/span><\/p>\n<p><span lang=\"FR-BE\"><strong>Stefan Vanistendael du BICE<\/strong> \u00e0 Gen\u00e8ve a prolong\u00e9 la r\u00e9flexion en expliquant que la r\u00e9silience s\u2019observe \u00e0 partir des cheminements de vie qui nous surprennent en bien. Il a d\u00e9velopp\u00e9 l\u2019importance d\u2019un regard sur l\u2019autre qui cherche le potentiel et les ressources de la personne au-del\u00e0 de ses seuls probl\u00e8mes. Il existe une d\u00e9marche pragmatique pour chercher du sens, facteur essentiel de la r\u00e9silience, en explorant tous les liens positifs, petits et grands, qui peuvent exister entre une personne et la vie autour d\u2019elle, entre autres par le r\u00e9cit de vie, les responsabilit\u00e9s adapt\u00e9es, les projets, la beaut\u00e9, ou la spiritualit\u00e9 chr\u00e9tienne qui est une invitation \u00e0 se lier toujours plus profond\u00e9ment \u00e0 la vie.<\/span><\/p>\n<p><span lang=\"FR-BE\">Si vous souhaitez en savoir plus sur la r\u00e9silience, nous vous invitons \u00e0 d\u00e9couvrir les <a href=\"https:\/\/bice.org\/fr\/publications-du-bice\/\">essais<\/a> de Stefan Vanistaendel publi\u00e9s par le BICE\u00a0: <em>Droits de l\u2019enfant et r\u00e9silience<\/em>, <em>La r\u00e9silience ou le r\u00e9alisme de l\u2019esp\u00e9rance<\/em>, <em>R\u00e9silience et Spiritualit<\/em><em>\u00e9<\/em>.<\/span><\/p>\n<p><strong><span lang=\"FR-BE\">La prochaine conf\u00e9rence pr\u00e9vue dans le cycle \u00ab\u00a0Enfance et Qu\u00eate de Sens\u00a0\u00bb aura lieu le jeudi 7 juin 2012 \u00e0 l\u2019Institut Catholique de Paris et portera sur la vision compar\u00e9e de l\u2019enfance par le prisme du christianisme et du bouddhisme.<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 12 avril dernier Stefan Vanistaendel, sociologue et chercheur au BICE, est intervenu en compagnie du Dr Michel Manciaux lors d\u2019une conf\u00e9rence passionnante sur la r\u00e9silience qui s\u2019ins\u00e9rait dans le cycle de conf\u00e9rence \u00ab\u00a0Enfance et qu\u00eate de sens\u00a0\u00bb co-organis\u00e9 par le BICE et l\u2019Institut Catholique de Paris.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[132],"tags":[],"class_list":["post-1004","post","type-post","status-publish","format-standard","hentry","category-actualites-du-bice"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La r\u00e9silience en question - BICE - ONG de protection des droits de l&#039;enfant<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/1004\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La r\u00e9silience en question - BICE - ONG de protection des droits de l&#039;enfant\" \/>\n<meta property=\"og:description\" content=\"Le 12 avril dernier Stefan Vanistaendel, sociologue et chercheur au BICE, est intervenu en compagnie du Dr Michel Manciaux lors d\u2019une conf\u00e9rence passionnante sur la r\u00e9silience qui s\u2019ins\u00e9rait dans le cycle de conf\u00e9rence \u00ab\u00a0Enfance et qu\u00eate de sens\u00a0\u00bb co-organis\u00e9 par le BICE et l\u2019Institut Catholique de Paris.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bice.org\/fr\/la-resilience-en-question\/\" \/>\n<meta property=\"og:site_name\" content=\"BICE - ONG de protection des droits de l&#039;enfant\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/OngBICE\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-20T14:33:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T10:20:54+00:00\" \/>\n<meta name=\"author\" content=\"BICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ongbice\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"BICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La r\u00e9silience en question - BICE - ONG de protection des droits de l&#039;enfant","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/1004","og_locale":"fr_FR","og_type":"article","og_title":"La r\u00e9silience en question - BICE - ONG de protection des droits de l&#039;enfant","og_description":"Le 12 avril dernier Stefan Vanistaendel, sociologue et chercheur au BICE, est intervenu en compagnie du Dr Michel Manciaux lors d\u2019une conf\u00e9rence passionnante sur la r\u00e9silience qui s\u2019ins\u00e9rait dans le cycle de conf\u00e9rence \u00ab\u00a0Enfance et qu\u00eate de sens\u00a0\u00bb co-organis\u00e9 par le BICE et l\u2019Institut Catholique de Paris.","og_url":"https:\/\/bice.org\/fr\/la-resilience-en-question\/","og_site_name":"BICE - ONG de protection des droits de l&#039;enfant","article_author":"https:\/\/www.facebook.com\/OngBICE","article_published_time":"2012-04-20T14:33:41+00:00","article_modified_time":"2023-02-02T10:20:54+00:00","author":"BICE","twitter_card":"summary_large_image","twitter_creator":"@ongbice","twitter_misc":{"\u00c9crit par":"BICE","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bice.org\/fr\/la-resilience-en-question\/#article","isPartOf":{"@id":"https:\/\/bice.org\/fr\/la-resilience-en-question\/"},"author":{"name":"BICE","@id":"https:\/\/bice.org\/fr\/#\/schema\/person\/5ffe567f32d0dbd204977300f4986f5b"},"headline":"La r\u00e9silience en question","datePublished":"2012-04-20T14:33:41+00:00","dateModified":"2023-02-02T10:20:54+00:00","mainEntityOfPage":{"@id":"https:\/\/bice.org\/fr\/la-resilience-en-question\/"},"wordCount":386,"publisher":{"@id":"https:\/\/bice.org\/fr\/#organization"},"articleSection":["Actualit\u00e9s du BICE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/bice.org\/fr\/la-resilience-en-question\/","url":"https:\/\/bice.org\/fr\/la-resilience-en-question\/","name":"La r\u00e9silience en question - BICE - ONG de protection des droits de l&#039;enfant","isPartOf":{"@id":"https:\/\/bice.org\/fr\/#website"},"datePublished":"2012-04-20T14:33:41+00:00","dateModified":"2023-02-02T10:20:54+00:00","breadcrumb":{"@id":"https:\/\/bice.org\/fr\/la-resilience-en-question\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bice.org\/fr\/la-resilience-en-question\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bice.org\/fr\/la-resilience-en-question\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bice.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s du BICE","item":"https:\/\/bice.org\/fr\/theme\/actualites-du-bice\/"},{"@type":"ListItem","position":3,"name":"La r\u00e9silience en question"}]},{"@type":"WebSite","@id":"https:\/\/bice.org\/fr\/#website","url":"https:\/\/bice.org\/fr\/","name":"BICE - ONG de protection des droits de l&#039;enfant","description":"Notre mission : D\u00e9fendre les droits et la dignit\u00e9 des enfants partout dans le monde","publisher":{"@id":"https:\/\/bice.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bice.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bice.org\/fr\/#organization","name":"BICE","url":"https:\/\/bice.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bice.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/bice.org\/app\/uploads\/2022\/06\/favicon.ico","contentUrl":"https:\/\/bice.org\/app\/uploads\/2022\/06\/favicon.ico","width":64,"height":64,"caption":"BICE"},"image":{"@id":"https:\/\/bice.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bice.org\/fr\/#\/schema\/person\/5ffe567f32d0dbd204977300f4986f5b","name":"BICE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2cef44cbc317f08498adbfd4c31e9d16fae93e3fb3589a01932b588cb583f93b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cef44cbc317f08498adbfd4c31e9d16fae93e3fb3589a01932b588cb583f93b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cef44cbc317f08498adbfd4c31e9d16fae93e3fb3589a01932b588cb583f93b?s=96&d=mm&r=g","caption":"BICE"},"description":"Articles et actualit\u00e9s du BICE","sameAs":["https:\/\/bice.org","https:\/\/www.facebook.com\/OngBICE","https:\/\/x.com\/ongbice"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/1004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/comments?post=1004"}],"version-history":[{"count":0,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/1004\/revisions"}],"wp:attachment":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/media?parent=1004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/categories?post=1004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/tags?post=1004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}