{"id":23131,"date":"2017-03-21T09:59:36","date_gmt":"2017-03-21T09:59:36","guid":{"rendered":"https:\/\/bice.org\/?p=23131\/"},"modified":"2019-05-10T11:34:13","modified_gmt":"2019-05-10T09:34:13","slug":"massacre-dans-un-foyer-d-accueil-au-guatemala","status":"publish","type":"post","link":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/","title":{"rendered":"Massacre dans un foyer d\u2019accueil au Guatemala"},"content":{"rendered":"<h2 style=\"text-align: justify;\">Trag\u00e9die dans un foyer d\u2019accueil au Guatemala<\/h2>\n<p style=\"text-align: justify;\">Ouvert en 2010, le foyer <em>Seguro Virgen<\/em> <em>de la Asunci\u00f3n<\/em> (<em>Foyer s\u00fbr de la Vierge de l\u2019Assomption<\/em>) est un foyer pour enfants situ\u00e9 \u00e0 San Jos\u00e9 Pinula, \u00e0 quelques kilom\u00e8tres de la capitale Guatemala City. Il accueille des enfants orphelins ou abandonn\u00e9s, des victimes de traite ou de violence intrafamiliale, ainsi que des jeunes en conflit avec la loi. Ses \u00e9ducateurs ont plusieurs fois \u00e9t\u00e9 d\u00e9nonc\u00e9s pour maltraitances et abus sexuels.<\/p>\n<p style=\"text-align: justify;\">Le 7 mars, un mouvement de r\u00e9bellion s\u2019est d\u00e9clench\u00e9 dans l\u2019aile des filles, certaines auraient pu mettre le feu \u00e0 leur matelas. Craignant que les jeunes filles n\u2019en profitent pour s\u2019enfuir, les \u00e9ducateurs ont bloqu\u00e9 les portes. 41 d\u2019entre elles sont d\u00e9c\u00e9d\u00e9es dans l\u2019incendie, plusieurs sont encore dans un \u00e9tat grave.<\/p>\n<h2 style=\"text-align: justify;\">Indignation des instances eccl\u00e9siales qui demandent justice pour les victimes<\/h2>\n<p style=\"text-align: justify;\">L\u2019indignation a gagn\u00e9 toute la soci\u00e9t\u00e9 guat\u00e9malt\u00e8que et les instances religieuses ont exprim\u00e9 publiquement leur incompr\u00e9hension et demand\u00e9 au gouvernement d\u2019agir afin qu\u2019une telle trag\u00e9die ne se reproduise plus.<br \/>\nLe jour m\u00eame, l\u2019<a href=\"https:\/\/bice.org\/fr\/odhag\/\">ODHAG<\/a> (Office dioc\u00e9sain pour les Droits de l\u2019Homme de l\u2019Archev\u00each\u00e9 de Guatemala, membre du BICE) exprimait sa profonde indignation quant \u00e0 l\u2019\u00e9tat d\u00e9plorable des foyers d\u2019accueil au Guatemala et exigeait la condamnation des responsables.<br \/>\nLe 9 mars, la Conf\u00e9rence des religieux et des religieuses s\u2019unissait aux familles dans la douleur et demandait au gouvernement de rendre justice. Elle a \u00e9t\u00e9 relay\u00e9e par le Pape Fran\u00e7ois, qui lors de l\u2019<a href=\"http:\/\/papefrancois.jeun.fr\/n2377-angelus-la-croix-nest-pas-un-bibelot-mais-un-rappel-de-lamour-de-jesus\" target=\"_blank\" rel=\"noopener\">Ang\u00e9lus du 12 mars<\/a> exprimait toute sa compassion au peuple guat\u00e9malt\u00e8que.<br \/>\nDans son <a href=\"http:\/\/www.iglesiacatolica.org.gt\/CEG-20170315.pdf\" target=\"_blank\" rel=\"noopener\">communiqu\u00e9<\/a> du 15 mars, la Conf\u00e9rence \u00e9piscopale guat\u00e9malt\u00e8que relevait, elle, que <em>\u00ab la mort tragique et les graves dommages subis par tant de jeunes filles qui auraient d\u00fb \u00eatre, dans ce centre, en s\u00e9curit\u00e9, respect\u00e9es pour trouver l\u2019aide et l\u2019orientation qu\u2019elles n\u2019avaient pas trouv\u00e9es dans leur famille et dans la soci\u00e9t\u00e9, n\u2019auraient pas d\u00fb se produire \u00bb<\/em>. Elle soulignait aussi que cet \u00e9v\u00e9nement \u00e9tait le fruit d\u2019un long processus de corruption et d\u2019impunit\u00e9 au Guatemala.<\/p>\n<h2 style=\"text-align: justify;\">Le BICE rappelle le Droit des enfants \u00e0 \u00eatre prot\u00e9g\u00e9s<\/h2>\n<p style=\"text-align: justify;\">Le pr\u00e9sident de la R\u00e9publique, Jimmy Morales, a ordonn\u00e9 la suspension du directeur du foyer et 3 jours de deuil national. Mais cela ne suffit pas.<\/p>\n<p style=\"text-align: justify;\">Le BICE se joint \u00e0 ce concert d\u2019indignations et rappelle le <a href=\"https:\/\/bice.org\/fr\/droits-de-lenfant\/convention-relative-aux-droits-de-l-enfant\/\">droit de chaque enfant \u00e0 vivre<\/a>, survivre et se d\u00e9velopper (art. 6 de la Convention des droits de l\u2019enfant), le droit \u00e0 \u00eatre prot\u00e9g\u00e9 contre toutes formes de violence (art. 19) et soign\u00e9 (art. 24). Il appuie la Conf\u00e9rence \u00e9piscopale qui r\u00e9clame des \u00ab r\u00e9formes constitutionnelles \u00bb pour mettre fin \u00e0 l\u2019impunit\u00e9 et \u00e0 la corruption et parvenir \u00e0 un Etat de droit qui garantisse une justice impartiale et \u00e9quitable, sp\u00e9cialement pour la protection des plus faibles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>39 jeunes filles sont d\u00e9c\u00e9d\u00e9es dans leur foyer au Guatemala, br\u00fbl\u00e9es vives. Un flot de protestations eccl\u00e9siales et sociales s\u2019est \u00e9lev\u00e9. Ce foyer, g\u00e9r\u00e9 par le Secr\u00e9tariat du Bien Etre Social, \u00e9tait depuis plusieurs ann\u00e9es d\u00e9nonc\u00e9 pour ses mauvais traitements. On craint, qu\u2019une fois encore, les responsables de cette trag\u00e9die restent impunis. <\/p>\n","protected":false},"author":3,"featured_media":23135,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[132],"tags":[358,347,1213,353,554],"class_list":["post-23131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-du-bice","tag-droits-de-lhomme","tag-guatemala","tag-justice","tag-maltraitance","tag-pape-francois"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Massacre dans un foyer d\u2019accueil au Guatemala<\/title>\n<meta name=\"description\" content=\"Le 8 mars 2017, au moins 39 adolescentes sont mortes br\u00fbl\u00e9es vives dans leur foyer, r\u00e9put\u00e9 pour les mauvais traitements inflig\u00e9s \u00e0 ses r\u00e9sidents.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/23131\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Massacre dans un foyer d\u2019accueil au Guatemala\" \/>\n<meta property=\"og:description\" content=\"Le 8 mars 2017, au moins 39 adolescentes sont mortes br\u00fbl\u00e9es vives dans leur foyer, r\u00e9put\u00e9 pour les mauvais traitements inflig\u00e9s \u00e0 ses r\u00e9sidents.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/\" \/>\n<meta property=\"og:site_name\" content=\"BICE - ONG de protection des droits de l&#039;enfant\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-21T09:59:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-10T09:34:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2017\/03\/News-Guatemala-%C2%A9Prensa-Libre-Hemeroteca.jpg?fit=1000%2C569&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"569\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"BICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"BICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Massacre dans un foyer d\u2019accueil au Guatemala","description":"Le 8 mars 2017, au moins 39 adolescentes sont mortes br\u00fbl\u00e9es vives dans leur foyer, r\u00e9put\u00e9 pour les mauvais traitements inflig\u00e9s \u00e0 ses r\u00e9sidents.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/23131","og_locale":"fr_FR","og_type":"article","og_title":"Massacre dans un foyer d\u2019accueil au Guatemala","og_description":"Le 8 mars 2017, au moins 39 adolescentes sont mortes br\u00fbl\u00e9es vives dans leur foyer, r\u00e9put\u00e9 pour les mauvais traitements inflig\u00e9s \u00e0 ses r\u00e9sidents.","og_url":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/","og_site_name":"BICE - ONG de protection des droits de l&#039;enfant","article_published_time":"2017-03-21T09:59:36+00:00","article_modified_time":"2019-05-10T09:34:13+00:00","og_image":[{"width":1000,"height":569,"url":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2017\/03\/News-Guatemala-%C2%A9Prensa-Libre-Hemeroteca.jpg?fit=1000%2C569&ssl=1","type":"image\/jpeg"}],"author":"BICE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"BICE","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/#article","isPartOf":{"@id":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/"},"author":{"name":"BICE","@id":"https:\/\/bice.org\/fr\/#\/schema\/person\/d2ad3c47fafb278234233a8cb54707b4"},"headline":"Massacre dans un foyer d\u2019accueil au Guatemala","datePublished":"2017-03-21T09:59:36+00:00","dateModified":"2019-05-10T09:34:13+00:00","mainEntityOfPage":{"@id":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/"},"wordCount":508,"publisher":{"@id":"https:\/\/bice.org\/fr\/#organization"},"image":{"@id":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2017\/03\/News-Guatemala-%C2%A9Prensa-Libre-Hemeroteca.jpg?fit=1000%2C569&ssl=1","keywords":["droits de l'homme","Guatemala","justice","maltraitance","Pape Fran\u00e7ois"],"articleSection":["Actualit\u00e9s du BICE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/","url":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/","name":"Massacre dans un foyer d\u2019accueil au Guatemala","isPartOf":{"@id":"https:\/\/bice.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/#primaryimage"},"image":{"@id":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2017\/03\/News-Guatemala-%C2%A9Prensa-Libre-Hemeroteca.jpg?fit=1000%2C569&ssl=1","datePublished":"2017-03-21T09:59:36+00:00","dateModified":"2019-05-10T09:34:13+00:00","description":"Le 8 mars 2017, au moins 39 adolescentes sont mortes br\u00fbl\u00e9es vives dans leur foyer, r\u00e9put\u00e9 pour les mauvais traitements inflig\u00e9s \u00e0 ses r\u00e9sidents.","breadcrumb":{"@id":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/#primaryimage","url":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2017\/03\/News-Guatemala-%C2%A9Prensa-Libre-Hemeroteca.jpg?fit=1000%2C569&ssl=1","contentUrl":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2017\/03\/News-Guatemala-%C2%A9Prensa-Libre-Hemeroteca.jpg?fit=1000%2C569&ssl=1","width":1000,"height":569,"caption":"\u00a9Prensa Libre - Hemeroteca \/ Erick Avila"},{"@type":"BreadcrumbList","@id":"https:\/\/bice.org\/fr\/massacre-dans-un-foyer-d-accueil-au-guatemala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bice.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s du BICE","item":"https:\/\/bice.org\/fr\/theme\/actualites-du-bice\/"},{"@type":"ListItem","position":3,"name":"Massacre dans un foyer d\u2019accueil au Guatemala"}]},{"@type":"WebSite","@id":"https:\/\/bice.org\/fr\/#website","url":"https:\/\/bice.org\/fr\/","name":"BICE - ONG de protection des droits de l&#039;enfant","description":"Notre mission : D\u00e9fendre les droits et la dignit\u00e9 des enfants partout dans le monde","publisher":{"@id":"https:\/\/bice.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bice.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bice.org\/fr\/#organization","name":"BICE","url":"https:\/\/bice.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bice.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/bice.org\/app\/uploads\/2022\/06\/favicon.ico","contentUrl":"https:\/\/bice.org\/app\/uploads\/2022\/06\/favicon.ico","width":64,"height":64,"caption":"BICE"},"image":{"@id":"https:\/\/bice.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bice.org\/fr\/#\/schema\/person\/d2ad3c47fafb278234233a8cb54707b4","name":"BICE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43bcfdb745dd80b8374b0aaa21c6dd30b2976a6bdea12b3018b51f255692facc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43bcfdb745dd80b8374b0aaa21c6dd30b2976a6bdea12b3018b51f255692facc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43bcfdb745dd80b8374b0aaa21c6dd30b2976a6bdea12b3018b51f255692facc?s=96&d=mm&r=g","caption":"BICE"}}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2017\/03\/News-Guatemala-%C2%A9Prensa-Libre-Hemeroteca.jpg?fit=1000%2C569&ssl=1","_links":{"self":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/23131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/comments?post=23131"}],"version-history":[{"count":0,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/23131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/media\/23135"}],"wp:attachment":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/media?parent=23131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/categories?post=23131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/tags?post=23131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}