{"id":33817,"date":"2018-09-03T08:11:53","date_gmt":"2018-09-03T08:11:53","guid":{"rendered":"https:\/\/bice.org\/?p=33817\/"},"modified":"2023-03-07T14:46:56","modified_gmt":"2023-03-07T13:46:56","slug":"aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire","status":"publish","type":"post","link":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/","title":{"rendered":"Aux c\u00f4t\u00e9s des enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire"},"content":{"rendered":"<p style=\"text-align: justify;\">La situation des enfants en conflit avec la loi (ECL) en C\u00f4te d\u2019Ivoire reste des plus critiques. Ces enfants peuvent \u00eatre d\u00e9tenus hors du cadre l\u00e9gal du pays, avec des adultes, et priv\u00e9s des soins et de l\u2019alimentation de base. Souvent en rupture avec leur famille, ils ne b\u00e9n\u00e9ficient d\u2019aucun soutien affectif ni d\u2019aucune aide \u00e0 la r\u00e9insertion.<\/p>\n<h2 style=\"text-align: justify;\">Soutenir les enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire<\/h2>\n<p style=\"text-align: justify;\">Dans le cadre du programme <a href=\"https:\/\/bice.org\/fr\/cote-d-ivoire-justice-des-mineurs\/\">Enfance sans barreaux<\/a>, le BICE soutient l\u2019ONG <a href=\"https:\/\/bice.org\/fr\/dde-ci\/\">Dignit\u00e9 et Droits pour les Enfants<\/a> en C\u00f4te d\u2019Ivoire (DDE-CI). Cette derni\u00e8re assure une assistance permanente et multidisciplinaire afin d\u2019humaniser, autant que possible les conditions de d\u00e9tention de ces enfants, mais \u00e9galement de leur donner une chance de reconstruire leur vie. Un appui alimentaire, sanitaire et m\u00e9dical est ainsi assur\u00e9 \u00e0 la Brigade de Protection des Mineurs (BPM) et au Centre d\u2019Observation des Mineurs (COM) d\u2019Abidjan. <strong>245 mineurs en conflit avec la loi au COM et 264 \u00e0 la BPM ont ainsi pu en b\u00e9n\u00e9ficier en 2017<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Aux besoins vitaux, s\u2019ajoute la n\u00e9cessit\u00e9 de soutenir affectivement et psychologiquement ces jeunes en situation de grande vuln\u00e9rabilit\u00e9. Avec le support de psychologues locaux, DDE-CI a ainsi mis en place diff\u00e9rentes mesures d\u2019accompagnement adapt\u00e9es aux situations sp\u00e9cifiques de chaque enfant. L\u2019objectif est de mieux connaitre l\u2019enfant, de l\u2019aider \u00e0 comprendre les dommages caus\u00e9s, et enfin de l\u2019inciter \u00e0 renouer avec sa famille et \u00e0 construire un projet de vie.<\/p>\n<h2 style=\"text-align: justify;\">Un appui psychosocial pour chaque enfant<\/h2>\n<p style=\"text-align: justify;\">Le travail ici est double : d\u2019une part avec l\u2019enfant infracteur et d\u2019autre part avec ses parents. En renouant les liens familiaux, l\u2019enfant a en effet plus de chance d\u2019\u00eatre lib\u00e9r\u00e9 (dans le cadre d\u2019une mesure alternative \u00e0 la d\u00e9tention) \u2013 les parents se portant garants \u2013 et de r\u00e9ussir sa r\u00e9int\u00e9gration sociale. Cette m\u00e9thodologie d\u2019intervention promeut une justice restauratrice.<\/p>\n<p style=\"text-align: justify;\">Lors du travail avec l\u2019enfant, l\u2019\u00e9coute active est une premi\u00e8re \u00e9tape indispensable. Il faut d\u2019abord comprendre l\u2019enfant, son histoire, sa personnalit\u00e9, et gagner sa confiance pour pouvoir ensuite l\u2019aider. Diff\u00e9rents outils (counseling, th\u00e9rapies cognitives, psycho\u00e9ducation, aide \u00e0 l\u2019\u00e9laboration du projet de vie) peuvent alors prendre le relais en fonction des besoins identifi\u00e9s. En 2017, DDE-CI a, de plus, instaur\u00e9 deux groupes de paroles de jeunes. Trois anciens ECL sont venus t\u00e9moigner aupr\u00e8s de 70 mineurs en d\u00e9tention de leur nouvelle vie, sur le principe de la \u00ab contagion positive \u00bb.<br \/>\nAu total, <strong>457 mineurs en conflit avec la loi en C\u00f4te d\u2019Ivoire ont re\u00e7u un appui psychosocial de DDE-CI sur la p\u00e9riode<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La mission aupr\u00e8s des parents d\u00e9bute, elle, bien souvent par un travail de recherche de localisation, de l\u2019ordre de \u00ab l\u2019aiguille dans la botte de foin \u00bb. Les enfants se sont depuis longtemps \u00e9loign\u00e9s de leurs proches et ne disposent plus que d\u2019informations tr\u00e8s sommaires \u00e0 leur sujet. Cette t\u00e2che, ardue, chronophage et souvent dangereuse porte n\u00e9anmoins ses fruits. Sur les 86 recherches, 66 ont abouti \u00e0 la lib\u00e9ration de l\u2019enfant. Dans le cas de relations plus conflictuelles, DDE-CI propose aux parents des s\u00e9ances de guidance ou des ateliers de parentalit\u00e9 positives pour renforcer leurs comp\u00e9tences \u00e9ducatives et faire \u00e9voluer leur regard sur leur enfant.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En C\u00f4te d\u2019Ivoire, comme dans de nombreux pays, les droits des enfants en conflit avec la loi sont souvent bafou\u00e9s dans l\u2019indiff\u00e9rence la plus totale. DDE-CI, le partenaire local du BICE, lutte contre cet abandon g\u00e9n\u00e9ralis\u00e9 et met tout en \u0153uvre pour r\u00e9ins\u00e9rer durablement ces enfants dans la soci\u00e9t\u00e9.<\/p>\n","protected":false},"author":3,"featured_media":33818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[132],"tags":[511,443,1396,1061,874,462,372,1327,787],"class_list":["post-33817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-du-bice","tag-afrique","tag-cote-divoire","tag-dde-ci","tag-enfance-sans-barreaux","tag-enfants-en-conflit-avec-la-loi","tag-justice-des-mineurs","tag-justice-juvenile","tag-parentalite-positive","tag-reinsertion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aupr\u00e8s des enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire<\/title>\n<meta name=\"description\" content=\"Enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire : comment la DDE-CI assure la r\u00e9insertion des enfants en conflit avec la loi ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/33817\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aupr\u00e8s des enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire\" \/>\n<meta property=\"og:description\" content=\"Enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire : comment la DDE-CI assure la r\u00e9insertion des enfants en conflit avec la loi ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/\" \/>\n<meta property=\"og:site_name\" content=\"BICE - ONG de protection des droits de l&#039;enfant\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-03T08:11:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-07T13:46:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2018\/09\/News-ECL-C%C3%B4te-dIvoire.jpg?fit=1000%2C435&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"BICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"BICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aupr\u00e8s des enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire","description":"Enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire : comment la DDE-CI assure la r\u00e9insertion des enfants en conflit avec la loi ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/33817","og_locale":"fr_FR","og_type":"article","og_title":"Aupr\u00e8s des enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire","og_description":"Enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire : comment la DDE-CI assure la r\u00e9insertion des enfants en conflit avec la loi ?","og_url":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/","og_site_name":"BICE - ONG de protection des droits de l&#039;enfant","article_published_time":"2018-09-03T08:11:53+00:00","article_modified_time":"2023-03-07T13:46:56+00:00","og_image":[{"width":1000,"height":435,"url":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2018\/09\/News-ECL-C%C3%B4te-dIvoire.jpg?fit=1000%2C435&ssl=1","type":"image\/jpeg"}],"author":"BICE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"BICE","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/#article","isPartOf":{"@id":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/"},"author":{"name":"BICE","@id":"https:\/\/bice.org\/fr\/#\/schema\/person\/d2ad3c47fafb278234233a8cb54707b4"},"headline":"Aux c\u00f4t\u00e9s des enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire","datePublished":"2018-09-03T08:11:53+00:00","dateModified":"2023-03-07T13:46:56+00:00","mainEntityOfPage":{"@id":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/"},"wordCount":591,"publisher":{"@id":"https:\/\/bice.org\/fr\/#organization"},"image":{"@id":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2018\/09\/News-ECL-C%C3%B4te-dIvoire.jpg?fit=1000%2C435&ssl=1","keywords":["Afrique","C\u00f4te d'Ivoire","DDE-CI","Enfance sans barreaux","enfants en conflit avec la loi","Justice des mineurs","justice juv\u00e9nile","parentalit\u00e9 positive","r\u00e9insertion"],"articleSection":["Actualit\u00e9s du BICE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/","url":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/","name":"Aupr\u00e8s des enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire","isPartOf":{"@id":"https:\/\/bice.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/#primaryimage"},"image":{"@id":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2018\/09\/News-ECL-C%C3%B4te-dIvoire.jpg?fit=1000%2C435&ssl=1","datePublished":"2018-09-03T08:11:53+00:00","dateModified":"2023-03-07T13:46:56+00:00","description":"Enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire : comment la DDE-CI assure la r\u00e9insertion des enfants en conflit avec la loi ?","breadcrumb":{"@id":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/#primaryimage","url":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2018\/09\/News-ECL-C%C3%B4te-dIvoire.jpg?fit=1000%2C435&ssl=1","contentUrl":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2018\/09\/News-ECL-C%C3%B4te-dIvoire.jpg?fit=1000%2C435&ssl=1","width":1000,"height":435,"caption":"\u00a9J. Naegelen"},{"@type":"BreadcrumbList","@id":"https:\/\/bice.org\/fr\/aux-cotes-des-enfants-en-conflit-avec-la-loi-en-cote-d-ivoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bice.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s du BICE","item":"https:\/\/bice.org\/fr\/theme\/actualites-du-bice\/"},{"@type":"ListItem","position":3,"name":"Aux c\u00f4t\u00e9s des enfants en conflit avec la loi en C\u00f4te d\u2019Ivoire"}]},{"@type":"WebSite","@id":"https:\/\/bice.org\/fr\/#website","url":"https:\/\/bice.org\/fr\/","name":"BICE - ONG de protection des droits de l&#039;enfant","description":"Notre mission : D\u00e9fendre les droits et la dignit\u00e9 des enfants partout dans le monde","publisher":{"@id":"https:\/\/bice.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bice.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bice.org\/fr\/#organization","name":"BICE","url":"https:\/\/bice.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bice.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/bice.org\/app\/uploads\/2022\/06\/favicon.ico","contentUrl":"https:\/\/bice.org\/app\/uploads\/2022\/06\/favicon.ico","width":64,"height":64,"caption":"BICE"},"image":{"@id":"https:\/\/bice.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bice.org\/fr\/#\/schema\/person\/d2ad3c47fafb278234233a8cb54707b4","name":"BICE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43bcfdb745dd80b8374b0aaa21c6dd30b2976a6bdea12b3018b51f255692facc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43bcfdb745dd80b8374b0aaa21c6dd30b2976a6bdea12b3018b51f255692facc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43bcfdb745dd80b8374b0aaa21c6dd30b2976a6bdea12b3018b51f255692facc?s=96&d=mm&r=g","caption":"BICE"}}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2018\/09\/News-ECL-C%C3%B4te-dIvoire.jpg?fit=1000%2C435&ssl=1","_links":{"self":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/33817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/comments?post=33817"}],"version-history":[{"count":0,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/33817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/media\/33818"}],"wp:attachment":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/media?parent=33817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/categories?post=33817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/tags?post=33817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}