{"id":36541,"date":"2019-03-28T16:52:27","date_gmt":"2019-03-28T15:52:27","guid":{"rendered":"https:\/\/bice.org\/?p=36541\/"},"modified":"2024-04-16T09:37:59","modified_gmt":"2024-04-16T07:37:59","slug":"tuteurs-afrique-du-sud","status":"publish","type":"post","link":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/","title":{"rendered":"Une formation \u00ab tuteurs de r\u00e9silience \u00bb pour la premi\u00e8re fois en Afrique du Sud"},"content":{"rendered":"<p>Dans le cadre du programme \u00ab\u00a0<a href=\"https:\/\/bice.org\/fr\/la-resilience-au-coeur-de-notre-action\/\">Tuteurs de r\u00e9silience\u00a0<\/a>\u00bb, le BICE a r\u00e9pondu \u00e0 une demande de la congr\u00e9gation des fr\u00e8res Maristes de faire une formation en Afrique du Sud. Elle s\u2019adressait \u00e0 des \u00e9ducateurs impliqu\u00e9s dans leur projet \u00ab\u00a0<a href=\"http:\/\/www.three2six.co.za\/\">Three2Six project<\/a>\u00a0\u00bb.<\/p>\n<h2>Un nouveau pays d\u2019action pour le BICE\u00a0: l\u2019Afrique du Sud<\/h2>\n<p>La formation \u00ab\u00a0Tuteurs de r\u00e9silience\u00a0\u00bb s\u2019est tenue de 22 au 26 f\u00e9vrier dernier au \u00ab\u00a0Sacred Heart College\u00a0\u00bb de Johannesburg. 17 personnes y ont particip\u00e9. 12 enseignants appartenant \u00e0 des \u00e9coles Maristes, 1 enseignant de la \u00ab\u00a0Yeoville Boys School\u00a0\u00bb, 2 de l\u2019\u00e9cole publique \u00ab\u00a0Yeoville Community School\u00a0\u00bb et 2 avocats de l\u2019association \u00ab\u00a0<a href=\"http:\/\/www.lhr.org.za\/\">Lawyers for Human Rights<\/a>\u00a0\u00bb.<\/p>\n<p>Les b\u00e9n\u00e9ficiaires finaux, environ 370 enfants, 350 familles et 3400 personnes d\u00e9plac\u00e9es, profiteront de la formation. Cette derni\u00e8re \u00e9tait divis\u00e9e en 4 modules. Le premier consistait en une pr\u00e9sentation du concept de r\u00e9silience. Le deuxi\u00e8me portait sur les relations entre migrations et traumatismes. Le troisi\u00e8me sur la fa\u00e7on dont les \u00e9ducateurs peuvent concr\u00e8tement appliquer le concept de r\u00e9silience aux enfants dont ils s\u2019occupent. Enfin, le dernier portait sur l\u2019appropriation du r\u00f4le de Tuteur par les participants.<\/p>\n<p>La formation avait l\u2019objectif de doter les \u00e9ducateurs pr\u00e9sents d\u2019outils aussi bien th\u00e9oriques que pratiques pour aider aux mieux les enfants traumatis\u00e9s.<\/p>\n<h2>L\u2019Afrique du Sud, un contexte social difficile<\/h2>\n<p>L\u2019Afrique du Sud accueille depuis de nombreuses ann\u00e9es des milliers de r\u00e9fugi\u00e9s et demandeurs d\u2019asile africains fuyant leur pays d\u2019origine. Dans ce contexte, l\u2019acc\u00e8s \u00e0 l\u2019\u00e9ducation pour les enfants migrants est extr\u00eamement probl\u00e9matique. Si tous les enfants sud-africains sont assur\u00e9s de pouvoir aller \u00e0 l\u2019\u00e9cole, c\u2019est loin d\u2019\u00eatre le cas pour les enfants migrants. Papiers d\u2019identit\u00e9, frais d\u2019inscription, x\u00e9nophobie, manque d\u2019information sur la mani\u00e8re de s\u2019inscrire \u00e0 l\u2019\u00e9cole, sont autant de barri\u00e8res difficiles \u00e0 franchir pour eux.<\/p>\n<p>Face \u00e0 cette situation inacceptable, les fr\u00e8res Maristes ont cr\u00e9\u00e9s en 2008 le \u00ab\u00a0Tree2Six Project\u00a0\u00bb. Ce projet a pour but d\u2019assurer \u00e0 ces enfants de pouvoir aller \u00e0 l\u2019\u00e9cole, quelle que soit leur nationalit\u00e9 ou situation. Leur institution, le \u00ab\u00a0Sacred Heart College\u00a0\u00bb, a \u00e9t\u00e9 la premi\u00e8re \u00e0 accueillir des migrants. 100 enfants ont d\u2019abord \u00e9t\u00e9 pris en charge. Ils y ont pu y profiter, en plus d\u2019une remise \u00e0 niveau scolaire, d\u2019une ambiance chaleureuse et familiale si n\u00e9cessaire \u00e0 ces enfants traumatis\u00e9s. Depuis, leur nombre a augment\u00e9 et ils sont \u00e0 pr\u00e9sent plus de 300. Tous b\u00e9n\u00e9ficient d\u2019une \u00e9ducation de qualit\u00e9 dans un espace qui encourage l\u2019inclusion, la compr\u00e9hension de l\u2019autre et la participation de l\u2019enfant.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le BICE, en collaboration avec les Maristes, a d\u00e9marr\u00e9 une formation \u00ab Tuteurs de r\u00e9silience \u00bb en Afrique du Sud. Une premi\u00e8re bienvenue dans un pays qui accueille de nombreux enfants d\u00e9plac\u00e9s.<\/p>\n","protected":false},"author":1,"featured_media":36555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[132],"tags":[400,1419,1628,1351,1739],"class_list":["post-36541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-du-bice","tag-education","tag-enfants-deplaces","tag-maristes","tag-resilience-2","tag-tree2six-project"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une formation \u00ab tuteurs de r\u00e9silience \u00bb pour la 1ere fois en Afrique du Sud - BICE-ONG<\/title>\n<meta name=\"description\" content=\"En Afrique du Sud, le BICE a pour la premi\u00e8re fois fait une formation \u00ab Tuteurs de r\u00e9silience \u00bb en collaboration avec les Maristes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/36541\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une formation \u00ab tuteurs de r\u00e9silience \u00bb pour la 1ere fois en Afrique du Sud - BICE-ONG\" \/>\n<meta property=\"og:description\" content=\"En Afrique du Sud, le BICE a pour la premi\u00e8re fois fait une formation \u00ab Tuteurs de r\u00e9silience \u00bb en collaboration avec les Maristes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/\" \/>\n<meta property=\"og:site_name\" content=\"BICE - ONG de protection des droits de l&#039;enfant\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/OngBICE\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-28T15:52:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-16T07:37:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2019\/03\/photo-news-afrique-du-sud.png?fit=1000%2C435&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"BICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ongbice\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"BICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une formation \u00ab tuteurs de r\u00e9silience \u00bb pour la 1ere fois en Afrique du Sud - BICE-ONG","description":"En Afrique du Sud, le BICE a pour la premi\u00e8re fois fait une formation \u00ab Tuteurs de r\u00e9silience \u00bb en collaboration avec les Maristes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/36541","og_locale":"fr_FR","og_type":"article","og_title":"Une formation \u00ab tuteurs de r\u00e9silience \u00bb pour la 1ere fois en Afrique du Sud - BICE-ONG","og_description":"En Afrique du Sud, le BICE a pour la premi\u00e8re fois fait une formation \u00ab Tuteurs de r\u00e9silience \u00bb en collaboration avec les Maristes.","og_url":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/","og_site_name":"BICE - ONG de protection des droits de l&#039;enfant","article_author":"https:\/\/www.facebook.com\/OngBICE","article_published_time":"2019-03-28T15:52:27+00:00","article_modified_time":"2024-04-16T07:37:59+00:00","og_image":[{"width":1000,"height":435,"url":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2019\/03\/photo-news-afrique-du-sud.png?fit=1000%2C435&ssl=1","type":"image\/png"}],"author":"BICE","twitter_card":"summary_large_image","twitter_creator":"@ongbice","twitter_misc":{"\u00c9crit par":"BICE","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/#article","isPartOf":{"@id":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/"},"author":{"name":"BICE","@id":"https:\/\/bice.org\/fr\/#\/schema\/person\/5ffe567f32d0dbd204977300f4986f5b"},"headline":"Une formation \u00ab tuteurs de r\u00e9silience \u00bb pour la premi\u00e8re fois en Afrique du Sud","datePublished":"2019-03-28T15:52:27+00:00","dateModified":"2024-04-16T07:37:59+00:00","mainEntityOfPage":{"@id":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/"},"wordCount":467,"publisher":{"@id":"https:\/\/bice.org\/fr\/#organization"},"image":{"@id":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2019\/03\/photo-news-afrique-du-sud.png?fit=1000%2C435&ssl=1","keywords":["\u00e9ducation","enfants d\u00e9plac\u00e9s","Maristes","R\u00e9silience","Tree2Six Project"],"articleSection":["Actualit\u00e9s du BICE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/","url":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/","name":"Une formation \u00ab tuteurs de r\u00e9silience \u00bb pour la 1ere fois en Afrique du Sud - BICE-ONG","isPartOf":{"@id":"https:\/\/bice.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/#primaryimage"},"image":{"@id":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2019\/03\/photo-news-afrique-du-sud.png?fit=1000%2C435&ssl=1","datePublished":"2019-03-28T15:52:27+00:00","dateModified":"2024-04-16T07:37:59+00:00","description":"En Afrique du Sud, le BICE a pour la premi\u00e8re fois fait une formation \u00ab Tuteurs de r\u00e9silience \u00bb en collaboration avec les Maristes.","breadcrumb":{"@id":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/#primaryimage","url":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2019\/03\/photo-news-afrique-du-sud.png?fit=1000%2C435&ssl=1","contentUrl":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2019\/03\/photo-news-afrique-du-sud.png?fit=1000%2C435&ssl=1","width":1000,"height":435,"caption":"Formation tuteurs de r\u00e9silience pour la 1ere fois en Afrique du Sud - BICE"},{"@type":"BreadcrumbList","@id":"https:\/\/bice.org\/fr\/tuteurs-afrique-du-sud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bice.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s du BICE","item":"https:\/\/bice.org\/fr\/theme\/actualites-du-bice\/"},{"@type":"ListItem","position":3,"name":"Une formation \u00ab tuteurs de r\u00e9silience \u00bb pour la premi\u00e8re fois en Afrique du Sud"}]},{"@type":"WebSite","@id":"https:\/\/bice.org\/fr\/#website","url":"https:\/\/bice.org\/fr\/","name":"BICE - ONG de protection des droits de l&#039;enfant","description":"Notre mission : D\u00e9fendre les droits et la dignit\u00e9 des enfants partout dans le monde","publisher":{"@id":"https:\/\/bice.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bice.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bice.org\/fr\/#organization","name":"BICE","url":"https:\/\/bice.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bice.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/bice.org\/app\/uploads\/2022\/06\/favicon.ico","contentUrl":"https:\/\/bice.org\/app\/uploads\/2022\/06\/favicon.ico","width":64,"height":64,"caption":"BICE"},"image":{"@id":"https:\/\/bice.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bice.org\/fr\/#\/schema\/person\/5ffe567f32d0dbd204977300f4986f5b","name":"BICE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2cef44cbc317f08498adbfd4c31e9d16fae93e3fb3589a01932b588cb583f93b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cef44cbc317f08498adbfd4c31e9d16fae93e3fb3589a01932b588cb583f93b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cef44cbc317f08498adbfd4c31e9d16fae93e3fb3589a01932b588cb583f93b?s=96&d=mm&r=g","caption":"BICE"},"description":"Articles et actualit\u00e9s du BICE","sameAs":["https:\/\/bice.org","https:\/\/www.facebook.com\/OngBICE","https:\/\/x.com\/ongbice"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/bice.org\/app\/uploads\/2019\/03\/photo-news-afrique-du-sud.png?fit=1000%2C435&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/36541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/comments?post=36541"}],"version-history":[{"count":0,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/posts\/36541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/media\/36555"}],"wp:attachment":[{"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/media?parent=36541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/categories?post=36541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bice.org\/fr\/wp-json\/wp\/v2\/tags?post=36541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}